{"id":597,"date":"2024-11-28T11:28:40","date_gmt":"2024-11-28T10:28:40","guid":{"rendered":"https:\/\/www.rers-evry-bdd.fr\/?page_id=597"},"modified":"2025-12-27T23:23:51","modified_gmt":"2025-12-27T22:23:51","slug":"exemple-echanges-de-savoirs-thesaurus","status":"publish","type":"page","link":"https:\/\/www.rers-evry-bdd.fr\/index.php\/page-en-construction-2\/exemple-echanges-de-savoirs-thesaurus\/","title":{"rendered":"Exemples d&rsquo;\u00e9changes de savoirs &#8211; th\u00e9saurus"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"597\" class=\"elementor elementor-597\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6482b6aa e-flex e-con-boxed e-con e-parent\" data-id=\"6482b6aa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-482e31b8 elementor-widget__width-inherit elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"482e31b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"938\" height=\"198\" src=\"https:\/\/www.rers-evry-bdd.fr\/wp-content\/uploads\/2025\/04\/bandeau_echanges_savoirs.webp\" class=\"attachment-large size-large wp-image-5549\" alt=\"\" srcset=\"https:\/\/www.rers-evry-bdd.fr\/wp-content\/uploads\/2025\/04\/bandeau_echanges_savoirs.webp 938w, https:\/\/www.rers-evry-bdd.fr\/wp-content\/uploads\/2025\/04\/bandeau_echanges_savoirs-300x63.webp 300w, https:\/\/www.rers-evry-bdd.fr\/wp-content\/uploads\/2025\/04\/bandeau_echanges_savoirs-768x162.webp 768w\" sizes=\"(max-width: 938px) 100vw, 938px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-662f4a01 e-flex e-con-boxed e-con e-parent\" data-id=\"662f4a01\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5c8b53b5 elementor-nav-menu__align-start elementor-nav-menu--dropdown-mobile elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"5c8b53b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;svg aria-hidden=\\&quot;true\\&quot; class=\\&quot;fa-svg-chevron-down e-font-icon-svg e-fas-chevron-down\\&quot; viewBox=\\&quot;0 0 448 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;layout&quot;:&quot;horizontal&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-5c8b53b5\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-6054\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/\" class=\"elementor-item menu-link\">Accueil<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-3654\"><a aria-expanded=\"false\" href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/qui-sommes-nous\/\" class=\"elementor-item menu-link\">Qui sommes-nous ?<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Permutateur de Menu\" aria-haspopup=\"true\"><\/span><span class=\"sub-arrow\"><svg aria-hidden=\"true\" class=\"fa-svg-chevron-down e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2562\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/nos-valeurs-rers\/\" class=\"elementor-sub-item menu-link\">Nos valeurs<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2563\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/charte-rers-centre-essonne\/\" class=\"elementor-sub-item menu-link\">Charte des RERS<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2564\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/presentation-des-equipes\/\" class=\"elementor-sub-item menu-link\">L\u2019association et son organisation<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-3788\"><a aria-expanded=\"false\" href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/communication\/\" class=\"elementor-sub-item menu-link\">La communication<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Permutateur de Menu\" aria-haspopup=\"true\"><\/span><span class=\"sub-arrow\"><svg aria-hidden=\"true\" class=\"fa-svg-chevron-down e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2572\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/communication\/lettres-du-rers\/\" class=\"elementor-sub-item menu-link\">Les Lettres RERS<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2550\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/communication\/lir-lien-inter-rers\/\" class=\"elementor-sub-item menu-link\">LIR Lien Inter RERS<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2565\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/partenaires-rers-centre-essonne\/\" class=\"elementor-sub-item menu-link\">Nos Partenaires<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-4585\"><a aria-expanded=\"false\" href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/foresco-le-mouvement-des-rers\/\" class=\"elementor-sub-item menu-link\">FORESCO le Mouvement des RERS<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Permutateur de Menu\" aria-haspopup=\"true\"><\/span><span class=\"sub-arrow\"><svg aria-hidden=\"true\" class=\"fa-svg-chevron-down e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8214\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/notre-histoire-nos-histoires-dans-le-reseau\/\" class=\"elementor-sub-item menu-link\">Fresque \u2013 Histoire des R\u00e9seaux<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4809\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/rencontres-automne-reseaux-des-rers\/\" class=\"elementor-sub-item menu-link\">Les Rencontres d\u2019automne<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3811\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/notre-histoire\/les-ags-de-foresco\/\" class=\"elementor-sub-item menu-link\">Les AGs de FORESCO<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-2566\"><a aria-expanded=\"false\" href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/notre-histoire\/\" class=\"elementor-sub-item menu-link\">Notre histoire<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Permutateur de Menu\" aria-haspopup=\"true\"><\/span><span class=\"sub-arrow\"><svg aria-hidden=\"true\" class=\"fa-svg-chevron-down e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7936\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/notre-histoire-nos-histoires-dans-le-reseau\/\" class=\"elementor-sub-item menu-link\">Fresque \u2013 Histoire des R\u00e9seaux<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7692\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/qui-sommes-nous\/fete-des-45-ans\/\" class=\"elementor-sub-item menu-link\">F\u00eate des 45 ans<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2611\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/page-en-construction-2\/\" class=\"elementor-sub-item menu-link\">F\u00eate des 50 de FORESCO<\/a><\/li>\n\t<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-4611\"><a aria-expanded=\"false\" href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/demandes-offres-savoirs-rers-centre-essonne\/echanges-de-savoirs-evry-essonne\/\" class=\"elementor-item menu-link\">\u00c9changes de Savoirs<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Permutateur de Menu\" aria-haspopup=\"true\"><\/span><span class=\"sub-arrow\"><svg aria-hidden=\"true\" class=\"fa-svg-chevron-down e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2568\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/demandes-offres-savoirs-rers-centre-essonne\/ca-se-passe-comment\/\" class=\"elementor-sub-item menu-link\">\u00c7a se passe comment ?<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2567\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/demandes-offres-savoirs-rers-centre-essonne\/\" class=\"elementor-sub-item menu-link\">Demandes\/Offres en attente\u2026<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-2974\"><a aria-expanded=\"false\" href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/demandes-offres-savoirs-rers-centre-essonne\/echanges-collectifs-en-cours\/\" class=\"elementor-sub-item menu-link\">\u00c9changes collectifs de savoirs en cours<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Permutateur de Menu\" aria-haspopup=\"true\"><\/span><span class=\"sub-arrow\"><svg aria-hidden=\"true\" class=\"fa-svg-chevron-down e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2569\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/demandes-offres-savoirs-rers-centre-essonne\/clas-rers-centre-essonne\/\" class=\"elementor-sub-item menu-link\">CLAS : les \u00e9changes de savoirs dans l\u2019accompagnement \u00e0 la scolarit\u00e9<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4949\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/demandes-offres-savoirs-rers-centre-essonne\/echanges-vacances-rers-centre-essonne\/\" class=\"elementor-sub-item menu-link\">Les \u00e9changes Vacances<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2578\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/demandes-offres-savoirs-rers-centre-essonne\/jardin-en-partage-rers-centre-essonne\/elementor-page-913\/\" class=\"elementor-sub-item menu-link\">Jardin en Partage<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3061\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/demandes-offres-savoirs-rers-centre-essonne\/echanges-collectifs-en-cours\/parlons-laicite\/\" class=\"elementor-sub-item menu-link\">Parlons La\u00efcit\u00e9<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4596\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/page-en-construction-2\/exemple-echanges-de-savoirs-thesaurus\/\" class=\"elementor-sub-item menu-link\">Exemples d\u2019\u00e9changes de savoirs \u2013 th\u00e9saurus<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-4553\"><a aria-expanded=\"false\" href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/nos-projets\/\" class=\"elementor-item menu-link\">Nos projets<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Permutateur de Menu\" aria-haspopup=\"true\"><\/span><span class=\"sub-arrow\"><svg aria-hidden=\"true\" class=\"fa-svg-chevron-down e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5020\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/projets-annee-rers-centre-essonne\/\" class=\"elementor-sub-item menu-link\">Les projets de l\u2019ann\u00e9e<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2577\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/clas-au-rers\/\" class=\"elementor-sub-item menu-link\">CLAS au RERS<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2570\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/demandes-offres-savoirs-rers-centre-essonne\/jardin-en-partage-rers-centre-essonne\/\" class=\"elementor-sub-item menu-link\">Jardin en Partage<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2554\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/ville-apprenante-evry-courcouronnes\/\" class=\"elementor-sub-item menu-link\">Avec \u00c9vry-Courcouronnes \u2013 Ville Apprenante<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-2555\"><a aria-expanded=\"false\" href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/demandes-offres-savoirs-rers-centre-essonne\/echanges-collectifs-en-cours\/formations-reciproques-rers\/\" class=\"elementor-item menu-link\">Nos formations<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Permutateur de Menu\" aria-haspopup=\"true\"><\/span><span class=\"sub-arrow\"><svg aria-hidden=\"true\" class=\"fa-svg-chevron-down e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4491\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/co-formation-interne\/\" class=\"elementor-sub-item menu-link\">Co-formation interne<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4496\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/formations-foresco\/\" class=\"elementor-sub-item menu-link\">Formations FORESCO<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2556\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/ou-nous-rencontrer-rers-centre-essonne\/\" class=\"elementor-item menu-link\">O\u00f9 nous trouver ?<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4454\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/ou-nous-rencontrer-rers-centre-essonne\/contacter-rers-evry-essonne\/\" class=\"elementor-item menu-link\">Nous contacter<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-5c8b53b5\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-6054\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Accueil<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-3654\"><a aria-expanded=\"false\" href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/qui-sommes-nous\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Qui sommes-nous ?<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Permutateur de Menu\" aria-haspopup=\"true\"><\/span><span class=\"sub-arrow\"><svg aria-hidden=\"true\" class=\"fa-svg-chevron-down e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2562\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/nos-valeurs-rers\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Nos valeurs<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2563\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/charte-rers-centre-essonne\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Charte des RERS<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2564\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/presentation-des-equipes\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">L\u2019association et son organisation<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-3788\"><a aria-expanded=\"false\" href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/communication\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">La communication<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Permutateur de Menu\" aria-haspopup=\"true\"><\/span><span class=\"sub-arrow\"><svg aria-hidden=\"true\" class=\"fa-svg-chevron-down e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2572\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/communication\/lettres-du-rers\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Les Lettres RERS<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2550\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/communication\/lir-lien-inter-rers\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">LIR Lien Inter RERS<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2565\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/partenaires-rers-centre-essonne\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Nos Partenaires<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-4585\"><a aria-expanded=\"false\" href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/foresco-le-mouvement-des-rers\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">FORESCO le Mouvement des RERS<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Permutateur de Menu\" aria-haspopup=\"true\"><\/span><span class=\"sub-arrow\"><svg aria-hidden=\"true\" class=\"fa-svg-chevron-down e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8214\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/notre-histoire-nos-histoires-dans-le-reseau\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Fresque \u2013 Histoire des R\u00e9seaux<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4809\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/rencontres-automne-reseaux-des-rers\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Les Rencontres d\u2019automne<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3811\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/notre-histoire\/les-ags-de-foresco\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Les AGs de FORESCO<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-2566\"><a aria-expanded=\"false\" href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/notre-histoire\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Notre histoire<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Permutateur de Menu\" aria-haspopup=\"true\"><\/span><span class=\"sub-arrow\"><svg aria-hidden=\"true\" class=\"fa-svg-chevron-down e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7936\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/notre-histoire-nos-histoires-dans-le-reseau\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Fresque \u2013 Histoire des R\u00e9seaux<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7692\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/qui-sommes-nous\/fete-des-45-ans\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">F\u00eate des 45 ans<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2611\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/page-en-construction-2\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">F\u00eate des 50 de FORESCO<\/a><\/li>\n\t<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-4611\"><a aria-expanded=\"false\" href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/demandes-offres-savoirs-rers-centre-essonne\/echanges-de-savoirs-evry-essonne\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">\u00c9changes de Savoirs<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Permutateur de Menu\" aria-haspopup=\"true\"><\/span><span class=\"sub-arrow\"><svg aria-hidden=\"true\" class=\"fa-svg-chevron-down e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2568\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/demandes-offres-savoirs-rers-centre-essonne\/ca-se-passe-comment\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">\u00c7a se passe comment ?<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2567\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/demandes-offres-savoirs-rers-centre-essonne\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Demandes\/Offres en attente\u2026<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-2974\"><a aria-expanded=\"false\" href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/demandes-offres-savoirs-rers-centre-essonne\/echanges-collectifs-en-cours\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">\u00c9changes collectifs de savoirs en cours<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Permutateur de Menu\" aria-haspopup=\"true\"><\/span><span class=\"sub-arrow\"><svg aria-hidden=\"true\" class=\"fa-svg-chevron-down e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2569\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/demandes-offres-savoirs-rers-centre-essonne\/clas-rers-centre-essonne\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">CLAS : les \u00e9changes de savoirs dans l\u2019accompagnement \u00e0 la scolarit\u00e9<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4949\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/demandes-offres-savoirs-rers-centre-essonne\/echanges-vacances-rers-centre-essonne\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Les \u00e9changes Vacances<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2578\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/demandes-offres-savoirs-rers-centre-essonne\/jardin-en-partage-rers-centre-essonne\/elementor-page-913\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Jardin en Partage<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3061\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/demandes-offres-savoirs-rers-centre-essonne\/echanges-collectifs-en-cours\/parlons-laicite\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Parlons La\u00efcit\u00e9<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4596\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/page-en-construction-2\/exemple-echanges-de-savoirs-thesaurus\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Exemples d\u2019\u00e9changes de savoirs \u2013 th\u00e9saurus<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-4553\"><a aria-expanded=\"false\" href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/nos-projets\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Nos projets<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Permutateur de Menu\" aria-haspopup=\"true\"><\/span><span class=\"sub-arrow\"><svg aria-hidden=\"true\" class=\"fa-svg-chevron-down e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5020\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/projets-annee-rers-centre-essonne\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Les projets de l\u2019ann\u00e9e<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2577\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/clas-au-rers\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">CLAS au RERS<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2570\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/demandes-offres-savoirs-rers-centre-essonne\/jardin-en-partage-rers-centre-essonne\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Jardin en Partage<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2554\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/ville-apprenante-evry-courcouronnes\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Avec \u00c9vry-Courcouronnes \u2013 Ville Apprenante<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-2555\"><a aria-expanded=\"false\" href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/demandes-offres-savoirs-rers-centre-essonne\/echanges-collectifs-en-cours\/formations-reciproques-rers\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Nos formations<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Permutateur de Menu\" aria-haspopup=\"true\"><\/span><span class=\"sub-arrow\"><svg aria-hidden=\"true\" class=\"fa-svg-chevron-down e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4491\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/co-formation-interne\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Co-formation interne<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4496\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/formations-foresco\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Formations FORESCO<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2556\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/ou-nous-rencontrer-rers-centre-essonne\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">O\u00f9 nous trouver ?<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4454\"><a href=\"https:\/\/www.rers-evry-bdd.fr\/index.php\/ou-nous-rencontrer-rers-centre-essonne\/contacter-rers-evry-essonne\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Nous contacter<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26c65e8 elementor-widget elementor-widget-page-title\" data-id=\"26c65e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"page-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\n\t\t<div class=\"hfe-page-title hfe-page-title-wrapper elementor-widget-heading\">\n\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.rers-evry-bdd.fr\">\n\t\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\n\t\t\t\t\t\t\t\t\n\t\t\t\tExemples d&rsquo;\u00e9changes de savoirs &#8211; th\u00e9saurus  \n\t\t\t<\/h1 > \n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-301e3c01 e-flex e-con-boxed e-con e-parent\" data-id=\"301e3c01\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-53bfca9e e-flex e-con-boxed e-con e-parent\" data-id=\"53bfca9e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-25fa240 e-con-full e-flex e-con e-child\" data-id=\"25fa240\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-892fda7 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"892fda7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"937\" height=\"600\" src=\"https:\/\/www.rers-evry-bdd.fr\/wp-content\/uploads\/2025\/03\/accueil_reciprocite.webp\" class=\"attachment-large size-large wp-image-4904\" alt=\"\" srcset=\"https:\/\/www.rers-evry-bdd.fr\/wp-content\/uploads\/2025\/03\/accueil_reciprocite.webp 937w, https:\/\/www.rers-evry-bdd.fr\/wp-content\/uploads\/2025\/03\/accueil_reciprocite-300x192.webp 300w, https:\/\/www.rers-evry-bdd.fr\/wp-content\/uploads\/2025\/03\/accueil_reciprocite-768x492.webp 768w\" sizes=\"(max-width: 937px) 100vw, 937px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6f93c942 e-con-full e-flex e-con e-child\" data-id=\"6f93c942\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ad28251 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"3ad28251\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"text-align: center;\">Les savoirs mentionn\u00e9s dans notre plaquette de pr\u00e9sentation<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3eb102 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"a3eb102\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.rers-evry-bdd.fr\/wp-content\/uploads\/2025\/03\/RERS_plaquette2024_thesaurus.webp\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">agrandir la liste<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1223a722 elementor-widget elementor-widget-image\" data-id=\"1223a722\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.rers-evry-bdd.fr\/wp-content\/uploads\/2025\/03\/RERS_plaquette2024_thesaurus.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"RERS_plaquette2024_thesaurus\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDk1MSwidXJsIjoiaHR0cHM6XC9cL3d3dy5yZXJzLWV2cnktYmRkLmZyXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wM1wvUkVSU19wbGFxdWV0dGUyMDI0X3RoZXNhdXJ1cy53ZWJwIn0%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.rers-evry-bdd.fr\/wp-content\/uploads\/elementor\/thumbs\/RERS_plaquette2024_thesaurus-r3dhh1j60das2mx5ykxa03h1axt323smrzhq3jicy0.webp\" title=\"RERS_plaquette2024_thesaurus\" alt=\"RERS_plaquette2024_thesaurus\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6b36e441 e-flex e-con-boxed e-con e-parent\" data-id=\"6b36e441\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7d1c561f elementor-widget elementor-widget-spacer\" data-id=\"7d1c561f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-be14d68 e-flex e-con-boxed e-con e-parent\" data-id=\"be14d68\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b7ffd2d elementor-widget elementor-widget-text-editor\" data-id=\"5b7ffd2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t\n<p class=\"wp-block-paragraph\"><strong>Un th\u00e9saurus pour vous donner des id\u00e9es et des envies&#8230;<\/strong><\/p>\n<p>\u00a0<\/p>\n<p><strong>Th\u00e9saurus\u00a0: <\/strong><strong>Des savoirs en abondance\u2026 <\/strong><strong>(Fait \u00e0 partir de quatre journaux de r\u00e9seaux)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">\u00a0<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c4faf21 e-flex e-con-boxed e-con e-parent\" data-id=\"c4faf21\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c394933 e-con-full e-flex e-con e-child\" data-id=\"c394933\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-66bbdcb elementor-widget elementor-widget-text-editor\" data-id=\"66bbdcb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>T\u00e9l\u00e9phoner<\/p>\n<p>Analyser les assurances<\/p>\n<p>Grammaire\u00a0: les subordonn\u00e9es relatives<\/p>\n<p>Braille\u00a0<\/p>\n<p>Broderie sur linges<\/p>\n<p>\u00c9quation et in\u00e9quations, niveau seconde<\/p>\n<p>Faire un site web<\/p>\n<p>Conduire \u00e9conomiquement<\/p>\n<p>Comment la renaissance renouvelle-t-elle les formes de l\u2019expression artistique (5<sup>\u00e8me<\/sup>)<\/p>\n<p>Confection de rideaux<\/p>\n<p>Utiliser mieux le t\u00e9l\u00e9phone mobile<\/p>\n<p>D\u00e9gustation des vins<\/p>\n<p>Fran\u00e7ais r\u00e9sum\u00e9 de textes<\/p>\n<p>Faire des enregistrements vid\u00e9o<\/p>\n<p>Connaitre les Gobelins<\/p>\n<p>M\u00e9canique simple pour voitures<\/p>\n<p>Mode, choix des styles, des couleurs<\/p>\n<p>Tricot<\/p>\n<p>Appuis scolaires<\/p>\n<p>Auto-\u00e9cole\u00a0<\/p>\n<p>Comptabilit\u00e9<\/p>\n<p>Dactylographie<\/p>\n<p>Naviguer sur Internet<\/p>\n<p>L\u2019alimentation saine<\/p>\n<p>Gestion et organisation<\/p>\n<p>Informatique<\/p>\n<p>Cd-rom<\/p>\n<p>Savoirs en \u00e9cologie<\/p>\n<p>Traitement de textes<\/p>\n<p>Introduction \u00e0 la physique<\/p>\n<p>Les strat\u00e9gies de marketing<\/p>\n<p>Math\u00e9matiques<\/p>\n<p>Physique de seconde<\/p>\n<p>Jeu de Rami<\/p>\n<p>Taille des arbres<\/p>\n<p>Comprendre les questions g\u00e9n\u00e9tiques<\/p>\n<p>Anglais d\u00e9butant<\/p>\n<p>Anglais conversation<\/p>\n<p>Espagnol d\u00e9butant<\/p>\n<p>Espagnol conversation<\/p>\n<p>Grammaire fran\u00e7aise<\/p>\n<p>Fran\u00e7ais conversation<\/p>\n<p>Fran\u00e7ais correspondance<\/p>\n<p>Fran\u00e7ais \u00e9crit<\/p>\n<p>Suisse\/allemand<\/p>\n<p>Cuisine asiatique<\/p>\n<p>Cuisine chinoise<\/p>\n<p>Cuisine \u00e9conomique<\/p>\n<p>Cuisine vietnamienne<\/p>\n<p>Desserts<\/p>\n<p>G\u00e2teaux au fromage<\/p>\n<p>Vacherin glac\u00e9<\/p>\n<p>Danse de salon<\/p>\n<p>D\u00e9coration d&rsquo;appartement<\/p>\n<p>Guitare<\/p>\n<p>Ikebana<\/p>\n<p>Peinture sur porcelaine<\/p>\n<p>Bio\u00e9thique<\/p>\n<p>\u00c9coute active<\/p>\n<p>Modifier des photos<\/p>\n<p>Natation<\/p>\n<p>Les techniques de jogging<\/p>\n<p>Tennis<\/p>\n<p>VTT<\/p>\n<p>Jardinage<\/p>\n<p>Courir le semi-marathon<\/p>\n<p>Coupe\/couture de base<\/p>\n<p>Danse folklorique<\/p>\n<p>Danse moderne<\/p>\n<p>Les exceptions en grammaire<\/p>\n<p>Jeu d\u2019\u00e9chec<\/p>\n<p>Danse urbaine<\/p>\n<p>P\u00e2tisserie orientale<\/p>\n<p>P\u00e2tisserie fran\u00e7aise<\/p>\n<p>Batterie<\/p>\n<p>Guitare s\u00e8che<\/p>\n<p>Guitare \u00e9lectrique<\/p>\n<p>Sant\u00e9, m\u00e9canismes de la maladie, fonctionnement du corps<\/p>\n<p>Travail du cuivre<\/p>\n<p>Crochet<\/p>\n<p>Dentelle<\/p>\n<p>Portugais<\/p>\n<p>Restauration de meuble<\/p>\n<p>Basket<\/p>\n<p>Les nombres complexes (programme de terminale)<\/p>\n<p>Nettoyage de chaudi\u00e8re\u00a0<\/p>\n<p>Jouer \u00e0 la belote<\/p>\n<p>Allemand conversation<\/p>\n<p>Allemand grammaire<\/p>\n<p>Analyse transactionnelle\u00a0<\/p>\n<p>Aquarelle<\/p>\n<p>Bridge<\/p>\n<p>Cartes de correspondance<\/p>\n<p>Reconnaissance des champignons<\/p>\n<p>Chant espagnol<\/p>\n<p>Code de la route<\/p>\n<p>Cuisine iranienne<\/p>\n<p>Dactylo<\/p>\n<p>Droit, le divorce<\/p>\n<p>Fran\u00e7ais orthographe\u00a0<\/p>\n<p>Fran\u00e7ais, lire, \u00e9crire, compter<\/p>\n<p>Fran\u00e7ais, prise de notes<\/p>\n<p>G\u00e9n\u00e9alogie<\/p>\n<p>Histoire de l&rsquo;hindouisme<\/p>\n<p>Histoire des religions<\/p>\n<p>Excel<\/p>\n<p>Italien<\/p>\n<p>Fabrication de jouets d&rsquo;enfants<\/p>\n<p>Langue des signes<\/p>\n<p>Maths, trigonom\u00e9trie<\/p>\n<p>Objets en p\u00e2te \u00e0 sel<\/p>\n<p>Percussions<\/p>\n<p>Philat\u00e9lie<\/p>\n<p>Photos\/d\u00e9veloppement<\/p>\n<p>Piano-d\u00e9butant<\/p>\n<p>Piano\/niveau moyen<\/p>\n<p>Poterie\/Raku<\/p>\n<p>Relaxation\/yoga<\/p>\n<p>Russe<\/p>\n<p>Tests psychotechniques<\/p>\n<p>Tissage, montage de la cha\u00eene<\/p>\n<p>Tissage\/initiation<\/p>\n<p>Vaincre la peur de l&rsquo;eau<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-88d646f e-con-full e-flex e-con e-child\" data-id=\"88d646f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7672d3b elementor-widget elementor-widget-text-editor\" data-id=\"7672d3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Organiser des randonn\u00e9es<\/p>\n<p>R\u00e9fection de chaises<\/p>\n<p>Connaitre les grandes religions<\/p>\n<p>Repassage<\/p>\n<p>Restauration de meubles<\/p>\n<p>Relaxation<\/p>\n<p>Roumain<\/p>\n<p>Secourisme, les gestes d&rsquo;urgence, application de r\u00e8gles de s\u00e9curit\u00e9<\/p>\n<p>Soins de la peau<\/p>\n<p>St\u00e9nographie<\/p>\n<p>Tapisserie<\/p>\n<p>Toilettage de chiens<\/p>\n<p>Torchis (recouvrir les murs de pl\u00e2tre style torchis)<\/p>\n<p>Philosophie des sciences<\/p>\n<p>\u00c9conomie<\/p>\n<p>Tresses africaines<\/p>\n<p>Ukrainien<\/p>\n<p>Organiser des voyages en groupe<\/p>\n<p>Histoire de la litt\u00e9rature d&rsquo;Am\u00e9rique latine<\/p>\n<p>Ma\u00eetrise de Word et Excel dans le cadre de recherche d&#8217;emploi<\/p>\n<p>Informatique d\u00e9butant<\/p>\n<p>Espagnol, en soutien \u00e0 des cours du CNED<\/p>\n<p>Apprendre \u00e0 se servir d&rsquo;un clavier<\/p>\n<p>D\u00e9couverte du m\u00e9tier d&rsquo;h\u00f4tesse d&rsquo;accueil (dans le cadre d&rsquo;une orientation professionnelle)<\/p>\n<p>Aide aux d\u00e9marches administratives<\/p>\n<p>Philosophie<\/p>\n<p>\u00c9changes sur des lectures<\/p>\n<p>D\u00e9couvertes de m\u00e9tiers<\/p>\n<p>Atelier d&rsquo;\u00e9criture<\/p>\n<p>M\u00e9canique auto<\/p>\n<p>Ma\u00e7onnerie<\/p>\n<p>\u00c9tymologie de la langue fran\u00e7aise<\/p>\n<p>D\u00e9couverte d&rsquo;internet<\/p>\n<p>Relaxation-sophrologie<\/p>\n<p>Introduction aux concepts psychanalytiques<\/p>\n<p>Chorale<\/p>\n<p>Macrophotographie<\/p>\n<p>D\u00e9couverte de l&rsquo;ordinateur, sa composition, son fonctionnement<\/p>\n<p>Anglais\/grammaire<\/p>\n<p>Arabe<\/p>\n<p>\u00a0Chinois d\u00e9butant<\/p>\n<p>Danse br\u00e9silienne<\/p>\n<p>Comptabilit\u00e9\/d\u00e9butant<\/p>\n<p>Portugais\/d\u00e9butant<\/p>\n<p>Arabe litt\u00e9raire<\/p>\n<p>Cuisine libanaise<\/p>\n<p>Cuisine \u00e9gyptienne<\/p>\n<p>Cuisine turque<\/p>\n<p>Anglais tous niveaux<\/p>\n<p>Biologie niveau seconde<\/p>\n<p>Maths jusqu&rsquo;\u00e0 la troisi\u00e8me<\/p>\n<p>Th\u00e9 \u00e0 la menthe<\/p>\n<p>D\u00e9couverte de la Tunisie<\/p>\n<p>Tapis faits mains<\/p>\n<p>Anglais jusqu&rsquo;\u00e0 Bac + 2<\/p>\n<p>Visite de la cath\u00e9drale d&rsquo;Evry<\/p>\n<p>Expliquer le m\u00e9tier d&rsquo;h\u00f4tesse d&rsquo;accueil Couture, lire un patron<\/p>\n<p>Les r\u00e8gles du foot<\/p>\n<p>Broderie tunisienne<\/p>\n<p>La langue Ourdou<\/p>\n<p>Cuisine italienne<\/p>\n<p>Conna\u00eetre la for\u00eat<\/p>\n<p>Poser du papier peint<\/p>\n<p>Cuisine ougandaise<\/p>\n<p>Gestion du stress<\/p>\n<p>Conseils en nutrition<\/p>\n<p>Bridge<\/p>\n<p>Se diriger en v\u00e9lo dans la ville<\/p>\n<p>Macram\u00e9<\/p>\n<p>Sels color\u00e9s<\/p>\n<p>Peinture \u00e0 l&rsquo;\u00e9ponge<\/p>\n<p>Cuisine malienne<\/p>\n<p>Physique niveau coll\u00e8ge<\/p>\n<p>Fl\u00fbte traversi\u00e8re<\/p>\n<p>\u00c9veil musical<\/p>\n<p>Danses pakistanaise<\/p>\n<p>D\u00e9couverte du Br\u00e9sil<\/p>\n<p>D\u00e9couverte des \u00c9tats-Unis \u00e0 partir de diapositives<\/p>\n<p>Quartiers de Paris<\/p>\n<p>Th\u00e9\u00e2tre-forum<\/p>\n<p>Faire des d\u00e9grad\u00e9s de couleurs<\/p>\n<p>Sculpture<\/p>\n<p>Bureautique<\/p>\n<p>Informatique, logiciel graphique<\/p>\n<p>Photo, prise de vues\u00a0<\/p>\n<p>Fran\u00e7ais, niveau troisi\u00e8me<\/p>\n<p>Prendre les transports en commun dans ma ville<\/p>\n<p>Exp\u00e9rience professionnelle dans le nettoyage industriel<\/p>\n<p>Apprendre \u00e0 \u00e9couter Schubert<\/p>\n<p>D\u00e9marches administratives<\/p>\n<p>Encadrement<\/p>\n<p>Porter les b\u00e9b\u00e9s dans le dos \u00e0 la m\u00e9thode indienne<\/p>\n<p>Droit du travail<\/p>\n<p>Th\u00e9\u00e2tre pour enfants<\/p>\n<p>Nourrir et soigner les animaux<\/p>\n<p>Japonais<\/p>\n<p>Iranien<\/p>\n<p>Traitement de texte, tableur<\/p>\n<p>Conversation fran\u00e7aise<\/p>\n<p>Ma\u00eetriser le fran\u00e7ais \u00e0 l&rsquo;\u00e9crit<\/p>\n<p>Patinage sur glace d\u00e9butant<\/p>\n<p>R\u00e9apprendre \u00e0 faire du v\u00e9lo<\/p>\n<p>Violon d\u00e9butant<\/p>\n<p>Maths, premi\u00e8re ann\u00e9e de Licence MASS<\/p>\n<p>Taille des rosiers<\/p>\n<p>G\u00e9om\u00e9trie et alg\u00e8bre<\/p>\n<p>Courriers administratifs<\/p>\n<p>Jouer du piano \u00e0 quatre mains<\/p>\n<p>Guitare \u00e9lectrique d\u00e9butant<\/p>\n<p>Soutien cours de litt\u00e9rature CNED<\/p>\n<p>Conna\u00eetre le G\u00e9n\u00e9thon<\/p>\n<p>Analyse de statistiques<\/p>\n<p>Histoire de la r\u00e9gion<\/p>\n<p>Les multiplications<\/p>\n<p>Peinture \u00e0 l&rsquo;huile<\/p>\n<p>Aquarelle<\/p>\n<p>Arm\u00e9nien<\/p>\n<p>Bambara<\/p>\n<p>Cam\u00e9scope<\/p>\n<p>Cartonnage<\/p>\n<p>Chant<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6557aee e-con-full e-flex e-con e-child\" data-id=\"6557aee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2474c4d elementor-widget elementor-widget-text-editor\" data-id=\"2474c4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Connaissance des couleurs<\/p>\n<p>Conversation allemande<\/p>\n<p>Danses africaines<\/p>\n<p>D\u00e9coration murale ext\u00e9rieure<\/p>\n<p>Esp\u00e9ranto<\/p>\n<p>G\u00e9ologie<\/p>\n<p>Gym-cerveau-m\u00e9moire<\/p>\n<p>Gym acrobatique<\/p>\n<p>Initiation photo<\/p>\n<p>Italien\u00a0<\/p>\n<p>Jeu de go<\/p>\n<p>Langue des signes<\/p>\n<p>Musculation<\/p>\n<p>Paillage de chaises<\/p>\n<p>Peinture<\/p>\n<p>Piscine<\/p>\n<p>R\u00e9fection si\u00e8ge-tapisserie<\/p>\n<p>Saxophone<\/p>\n<p>Sorties en famille<\/p>\n<p>Stretching<\/p>\n<p>Aide aux traductions anglais\/fran\u00e7ais<\/p>\n<p>Aide \u00e0 la r\u00e9daction de documents administratifs<\/p>\n<p>Bricolage<\/p>\n<p>Courriers administratifs, r\u00e9clamation<\/p>\n<p>Course \u00e0 pied<\/p>\n<p>D\u00e9coupe bois<\/p>\n<p>Di\u00e9t\u00e9tique<\/p>\n<p>\u00c9lectricit\u00e9 domestique<\/p>\n<p>Fonctionnement d&rsquo;une machine \u00e0 coudre moderne<\/p>\n<p>H\u00e9breu<\/p>\n<p>Initiation comptable<\/p>\n<p>Initiation roller<\/p>\n<p>Installation artistique<\/p>\n<p>Jeu de dames<\/p>\n<p>Jeux de soci\u00e9t\u00e9<\/p>\n<p>Lecture de po\u00e8mes<\/p>\n<p>Les colles<\/p>\n<p>Madison<\/p>\n<p>M\u00e9t\u00e9orologie<\/p>\n<p>N\u00e9erlandais<\/p>\n<p>Pain perdu<\/p>\n<p>Patchwork machine<\/p>\n<p>Peinture b\u00e2timent<\/p>\n<p>Peinture sur soie<\/p>\n<p>P\u00e9tanque<\/p>\n<p>Ping-pong<\/p>\n<p>Pochoirs<\/p>\n<p>Remaillage<\/p>\n<p>S&rsquo;occuper de petits rongeurs<\/p>\n<p>Scrabble<\/p>\n<p>Vitrerie<\/p>\n<p>Visite du Louvre<\/p>\n<p>Peinture sur verre<\/p>\n<p>Calligraphie arabe<\/p>\n<p>Menuiserie<\/p>\n<p>Harmonica<\/p>\n<p>Le persan \u00e9crit et parl\u00e9<\/p>\n<p>Langage des sourds et muets<\/p>\n<p>G\u00e9ologie<\/p>\n<p>Dressage de chiens<\/p>\n<p>Diabolo (jeu d&rsquo;adresse)<\/p>\n<p>Tours de magie<\/p>\n<p>Judo d\u00e9butant<\/p>\n<p>Yoga<\/p>\n<p>Boxe fran\u00e7aise<\/p>\n<p>Manucure\/p\u00e9dicure<\/p>\n<p>Les entretiens d&#8217;embauche<\/p>\n<p>S&rsquo;orienter avec une boussole et une carte<\/p>\n<p>Initiation aux travaux agricoles<\/p>\n<p>Utilisation du mat\u00e9riel agricole<\/p>\n<p>Am\u00e9nagement de cuisines<\/p>\n<p>Animation d&rsquo;un groupe de lecture<\/p>\n<p>Animation d&rsquo;un caf\u00e9 de philosophie<\/p>\n<p>Anthropologie initiation<\/p>\n<p>Arboriculture, reconnaissance des arbres<\/p>\n<p>Billard<\/p>\n<p>Biologie de 3<sup>\u00e8me<\/sup> \u00e0 BEP<\/p>\n<p>Bracelets br\u00e9siliens<\/p>\n<p>Braille, l&rsquo;alphabet<\/p>\n<p>Canevas d\u00e9butant<\/p>\n<p>Carrelage<\/p>\n<p>Charpente<\/p>\n<p>Conseils en chauffage<\/p>\n<p>Chimie de 3<sup>\u00e8me<\/sup> \u00e0 BEP<\/p>\n<p>Chorale enfants<\/p>\n<p>Coiffure, coupe, permanente, coloration<\/p>\n<p>Connaissance de Bachelard<\/p>\n<p>Connaissance de soi et des relations humaines d&rsquo;apr\u00e8s les \u00e9crits de Carl Rogers<\/p>\n<p>Contorsionisme sur rouleau<\/p>\n<p>Histoire<\/p>\n<p>G\u00e9ographie<\/p>\n<p>R\u00e9alisation d&rsquo;un <em>curriculum vitae<\/em><\/p>\n<p>Dresser une table de f\u00eate<\/p>\n<p>Droits sociaux<\/p>\n<p>Ethnologie, initiation<\/p>\n<p>D\u00e9chiffrage de partition folk pour guitare<\/p>\n<p>Histoire g\u00e9n\u00e9rale<\/p>\n<p>Arch\u00e9ologie<\/p>\n<p>Histoire pr\u00e9colombienne et conqu\u00eate de l&rsquo;Am\u00e9rique<\/p>\n<p>Histoire des civilisations du 20<sup>\u00e8me<\/sup> si\u00e8cle<\/p>\n<p>Tournage sur bois<\/p>\n<p>Pose de moquette<\/p>\n<p>Initiation au tam-tam<\/p>\n<p>D\u00e9couverte du jazz, de la musique baroque, de la musique m\u00e9di\u00e9vale, de la musique classique<\/p>\n<p>Origami<\/p>\n<p>P\u00eache<\/p>\n<p>Clarinette perfectionnement<\/p>\n<p>Cuisine courante et \u00e9conomique<\/p>\n<p>Dessin artistique, aquarelle, encre, fusain, crayons<\/p>\n<p>D\u00e9pannage \u00e9lectrom\u00e9nager<\/p>\n<p>Histoire du compagnonnage<\/p>\n<p>Initiation \u00e0 l&rsquo;\u00e9lectronique<\/p>\n<p>Technique de l&#8217;emp\u00e2tement sur bois<\/p>\n<p>Foot acrobatique<\/p>\n<p>Greffe d&rsquo;un citronnier<\/p>\n<p>Latin initiation<\/p>\n<p>Masques de cuir<\/p>\n<p>Plomberie<\/p>\n<p>Programmation neurolinguistique<\/p>\n<p>Sociologie et histoire des mentalit\u00e9s de la vie quotidienne de l&rsquo;an 1000 \u00e0 l&rsquo;an 1250<\/p>\n<p>Soudure \u00e0 l&rsquo;arc<\/p>\n<p>Connaissances des \u0153uvres et des th\u00e9ories de\u00a0 Pierre Bourdieu\u2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-00903c1 e-flex e-con-boxed e-con e-parent\" data-id=\"00903c1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5014a5b elementor-widget elementor-widget-text-editor\" data-id=\"5014a5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Et ceci, \u00e0 l\u2019infini\u2026 (Fait \u00e0 partir de quatre journaux de r\u00e9seaux)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <br \/><\/strong><\/p>\n<p><strong> CHS<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-39c61ce4 e-flex e-con-boxed e-con e-parent\" data-id=\"39c61ce4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ace4e46 elementor-widget elementor-widget-spacer\" data-id=\"7ace4e46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3920aba4 e-flex e-con-boxed e-con e-parent\" data-id=\"3920aba4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6ee868e2 elementor-widget elementor-widget-spacer\" data-id=\"6ee868e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-266e703f e-flex e-con-boxed e-con e-parent\" data-id=\"266e703f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22286085 elementor-widget elementor-widget-spacer\" data-id=\"22286085\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Exemples d&rsquo;\u00e9changes de savoirs &#8211; th\u00e9saurus Les savoirs mentionn\u00e9s dans notre plaquette de pr\u00e9sentation agrandir la liste Un th\u00e9saurus pour vous donner des id\u00e9es et des envies&#8230; \u00a0 Th\u00e9saurus\u00a0: Des [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5549,"parent":1366,"menu_order":8,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"class_list":["post-597","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/www.rers-evry-bdd.fr\/wp-content\/uploads\/2025\/04\/bandeau_echanges_savoirs.webp",938,198,false],"thumbnail":["https:\/\/www.rers-evry-bdd.fr\/wp-content\/uploads\/2025\/04\/bandeau_echanges_savoirs-150x150.webp",150,150,true],"medium":["https:\/\/www.rers-evry-bdd.fr\/wp-content\/uploads\/2025\/04\/bandeau_echanges_savoirs-300x63.webp",300,63,true],"medium_large":["https:\/\/www.rers-evry-bdd.fr\/wp-content\/uploads\/2025\/04\/bandeau_echanges_savoirs-768x162.webp",768,162,true],"large":["https:\/\/www.rers-evry-bdd.fr\/wp-content\/uploads\/2025\/04\/bandeau_echanges_savoirs.webp",938,198,false],"1536x1536":["https:\/\/www.rers-evry-bdd.fr\/wp-content\/uploads\/2025\/04\/bandeau_echanges_savoirs.webp",938,198,false],"2048x2048":["https:\/\/www.rers-evry-bdd.fr\/wp-content\/uploads\/2025\/04\/bandeau_echanges_savoirs.webp",938,198,false]},"uagb_author_info":{"display_name":"fbred","author_link":"https:\/\/www.rers-evry-bdd.fr\/author\/fbred\/"},"uagb_comment_info":0,"uagb_excerpt":"Exemples d&rsquo;\u00e9changes de savoirs &#8211; th\u00e9saurus Les savoirs mentionn\u00e9s dans notre plaquette de pr\u00e9sentation agrandir la liste Un th\u00e9saurus pour vous donner des id\u00e9es et des envies&#8230; \u00a0 Th\u00e9saurus\u00a0: Des [&hellip;]","_links":{"self":[{"href":"https:\/\/www.rers-evry-bdd.fr\/index.php\/wp-json\/wp\/v2\/pages\/597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rers-evry-bdd.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.rers-evry-bdd.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.rers-evry-bdd.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rers-evry-bdd.fr\/index.php\/wp-json\/wp\/v2\/comments?post=597"}],"version-history":[{"count":66,"href":"https:\/\/www.rers-evry-bdd.fr\/index.php\/wp-json\/wp\/v2\/pages\/597\/revisions"}],"predecessor-version":[{"id":8168,"href":"https:\/\/www.rers-evry-bdd.fr\/index.php\/wp-json\/wp\/v2\/pages\/597\/revisions\/8168"}],"up":[{"embeddable":true,"href":"https:\/\/www.rers-evry-bdd.fr\/index.php\/wp-json\/wp\/v2\/pages\/1366"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rers-evry-bdd.fr\/index.php\/wp-json\/wp\/v2\/media\/5549"}],"wp:attachment":[{"href":"https:\/\/www.rers-evry-bdd.fr\/index.php\/wp-json\/wp\/v2\/media?parent=597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}